{"id":3489,"date":"2019-03-17T10:07:29","date_gmt":"2019-03-17T10:07:29","guid":{"rendered":"http:\/\/www.manage.lru.ac.th\/th\/?p=3489"},"modified":"2019-03-17T10:07:41","modified_gmt":"2019-03-17T10:07:41","slug":"%e0%b8%aa%e0%b8%b2%e0%b8%82%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%99%e0%b8%b4%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-%e0%b8%a1%e0%b8%ab%e0%b8%b2","status":"publish","type":"post","link":"https:\/\/manage.lru.ac.th\/th\/%e0%b8%aa%e0%b8%b2%e0%b8%82%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%99%e0%b8%b4%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-%e0%b8%a1%e0%b8%ab%e0%b8%b2\/","title":{"rendered":"\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e25\u0e22 \u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21 \u201c\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e31\u0e01\u0e19\u0e34\u0e40\u0e17\u0e28\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u201d?? \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c (graphic design) \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e"},"content":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16-17 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2562 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e25\u0e22 \u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21 \u201c\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e31\u0e01\u0e19\u0e34\u0e40\u0e17\u0e28\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u201d?? \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c (graphic design) \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e08\u0e32\u0e01 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e20\u0e32\u0e13\u0e38\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e01\u0e32\u0e2b\u0e25\u0e34\u0e1a \u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e2a\u0e27\u0e19\u0e2a\u0e38\u0e19\u0e31\u0e19\u0e17\u0e32 \u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e25\u0e22 \u0e02\u0e2d\u0e02\u0e2d\u0e1a\u0e1e\u0e23\u0e30\u0e04\u0e38\u0e13 \u0e13 \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49 ?? #\u0e40\u0e14\u0e47\u0e01\u0e19\u0e34\u0e40\u0e17\u0e28\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c #wearecommartsLRU #\u0e04\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e2a\u0e37\u0e48\u0e2d #\u0e19\u0e34\u0e40\u0e17\u0e28\u0e2f\u0e40\u0e25\u0e22 \u2764\ufe0f<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-3490\" src=\"http:\/\/www.manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/61F5C53C-4A98-4D7F-958C-0B52F1C70DD2.jpeg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/61F5C53C-4A98-4D7F-958C-0B52F1C70DD2.jpeg 960w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/61F5C53C-4A98-4D7F-958C-0B52F1C70DD2-300x200.jpeg 300w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/61F5C53C-4A98-4D7F-958C-0B52F1C70DD2-768x512.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-3491\" src=\"http:\/\/www.manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/DFFD0E72-9A67-4FC2-A274-8390BF8C1BB5.jpeg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/DFFD0E72-9A67-4FC2-A274-8390BF8C1BB5.jpeg 960w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/DFFD0E72-9A67-4FC2-A274-8390BF8C1BB5-300x200.jpeg 300w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/DFFD0E72-9A67-4FC2-A274-8390BF8C1BB5-768x512.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img decoding=\"async\" class=\"alignnone size-full wp-image-3492\" src=\"http:\/\/www.manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/DE084769-8727-4D16-9B2B-AD6D44B1436E.jpeg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/DE084769-8727-4D16-9B2B-AD6D44B1436E.jpeg 960w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/DE084769-8727-4D16-9B2B-AD6D44B1436E-300x200.jpeg 300w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/DE084769-8727-4D16-9B2B-AD6D44B1436E-768x512.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3493\" src=\"http:\/\/www.manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/E7F5F50D-5527-48F5-917E-A80E5C734A0C.jpeg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/E7F5F50D-5527-48F5-917E-A80E5C734A0C.jpeg 960w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/E7F5F50D-5527-48F5-917E-A80E5C734A0C-300x225.jpeg 300w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/E7F5F50D-5527-48F5-917E-A80E5C734A0C-768x576.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3494\" src=\"http:\/\/www.manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/3358DF2B-54FA-4E79-91FA-B338DD06450F.jpeg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/3358DF2B-54FA-4E79-91FA-B338DD06450F.jpeg 960w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/3358DF2B-54FA-4E79-91FA-B338DD06450F-300x225.jpeg 300w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/3358DF2B-54FA-4E79-91FA-B338DD06450F-768x576.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3495\" src=\"http:\/\/www.manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/036E46D4-7F15-4288-8FB6-A405230AE131.jpeg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/036E46D4-7F15-4288-8FB6-A405230AE131.jpeg 960w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/036E46D4-7F15-4288-8FB6-A405230AE131-300x225.jpeg 300w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/036E46D4-7F15-4288-8FB6-A405230AE131-768x576.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3496\" src=\"http:\/\/www.manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/6DEA0274-D7E5-483A-8F34-81302D25F5FF.jpeg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/6DEA0274-D7E5-483A-8F34-81302D25F5FF.jpeg 960w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/6DEA0274-D7E5-483A-8F34-81302D25F5FF-300x200.jpeg 300w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/6DEA0274-D7E5-483A-8F34-81302D25F5FF-768x512.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3497\" src=\"http:\/\/www.manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/AFDFF921-3A97-4565-A918-6089550A2A54.jpeg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/AFDFF921-3A97-4565-A918-6089550A2A54.jpeg 960w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/AFDFF921-3A97-4565-A918-6089550A2A54-300x225.jpeg 300w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/AFDFF921-3A97-4565-A918-6089550A2A54-768x576.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3498\" src=\"http:\/\/www.manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/CA5F01F1-C771-47EA-9821-8FD1046BFD3D.jpeg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/CA5F01F1-C771-47EA-9821-8FD1046BFD3D.jpeg 960w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/CA5F01F1-C771-47EA-9821-8FD1046BFD3D-300x225.jpeg 300w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/CA5F01F1-C771-47EA-9821-8FD1046BFD3D-768x576.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3499\" src=\"http:\/\/www.manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/401945E9-DAC4-42EC-81B8-4EF91430F07B.jpeg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/401945E9-DAC4-42EC-81B8-4EF91430F07B.jpeg 960w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/401945E9-DAC4-42EC-81B8-4EF91430F07B-300x225.jpeg 300w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/401945E9-DAC4-42EC-81B8-4EF91430F07B-768x576.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3500\" src=\"http:\/\/www.manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/96B2E9C2-4706-4126-8132-F57E0B089024.jpeg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/96B2E9C2-4706-4126-8132-F57E0B089024.jpeg 960w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/96B2E9C2-4706-4126-8132-F57E0B089024-300x200.jpeg 300w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/96B2E9C2-4706-4126-8132-F57E0B089024-768x512.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3501\" src=\"http:\/\/www.manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/120929A5-5309-41F6-9331-087E50CCA395.jpeg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/120929A5-5309-41F6-9331-087E50CCA395.jpeg 960w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/120929A5-5309-41F6-9331-087E50CCA395-300x225.jpeg 300w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/120929A5-5309-41F6-9331-087E50CCA395-768x576.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3502\" src=\"http:\/\/www.manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/060DF89D-B053-421B-B970-456731CC9603.jpeg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/060DF89D-B053-421B-B970-456731CC9603.jpeg 960w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/060DF89D-B053-421B-B970-456731CC9603-300x225.jpeg 300w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/060DF89D-B053-421B-B970-456731CC9603-768x576.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3503\" src=\"http:\/\/www.manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/B6CC8B8F-D196-4838-9C3A-62A43DB38E35.jpeg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/B6CC8B8F-D196-4838-9C3A-62A43DB38E35.jpeg 960w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/B6CC8B8F-D196-4838-9C3A-62A43DB38E35-300x225.jpeg 300w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/B6CC8B8F-D196-4838-9C3A-62A43DB38E35-768x576.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3504\" src=\"http:\/\/www.manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/1258C512-45E5-40AA-BDC4-DCDA7BEF37C0.jpeg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/1258C512-45E5-40AA-BDC4-DCDA7BEF37C0.jpeg 960w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/1258C512-45E5-40AA-BDC4-DCDA7BEF37C0-300x200.jpeg 300w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/1258C512-45E5-40AA-BDC4-DCDA7BEF37C0-768x512.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3505\" src=\"http:\/\/www.manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/8EC1312B-6B0D-4C56-9D63-626478FA995D.jpeg\" alt=\"\" width=\"960\" height=\"640\" srcset=\"https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/8EC1312B-6B0D-4C56-9D63-626478FA995D.jpeg 960w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/8EC1312B-6B0D-4C56-9D63-626478FA995D-300x200.jpeg 300w, https:\/\/manage.lru.ac.th\/th\/wp-content\/uploads\/2019\/03\/8EC1312B-6B0D-4C56-9D63-626478FA995D-768x512.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16-17 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 <\/p>\n","protected":false},"author":1,"featured_media":3492,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[7],"tags":[],"class_list":["post-3489","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-7"],"_links":{"self":[{"href":"https:\/\/manage.lru.ac.th\/th\/wp-json\/wp\/v2\/posts\/3489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manage.lru.ac.th\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manage.lru.ac.th\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manage.lru.ac.th\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/manage.lru.ac.th\/th\/wp-json\/wp\/v2\/comments?post=3489"}],"version-history":[{"count":0,"href":"https:\/\/manage.lru.ac.th\/th\/wp-json\/wp\/v2\/posts\/3489\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manage.lru.ac.th\/th\/wp-json\/wp\/v2\/media\/3492"}],"wp:attachment":[{"href":"https:\/\/manage.lru.ac.th\/th\/wp-json\/wp\/v2\/media?parent=3489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manage.lru.ac.th\/th\/wp-json\/wp\/v2\/categories?post=3489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manage.lru.ac.th\/th\/wp-json\/wp\/v2\/tags?post=3489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}